{"id":80,"date":"2021-09-16T16:31:17","date_gmt":"2021-09-16T14:31:17","guid":{"rendered":"https:\/\/jczeller.com\/de\/?page_id=80"},"modified":"2025-09-23T13:11:01","modified_gmt":"2025-09-23T11:11:01","slug":"journalismus","status":"publish","type":"page","link":"https:\/\/jczeller.com\/de\/journalismus\/","title":{"rendered":"Journalismus"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"technik-gesellschaft-die-zukunft-meine-arbeit-als-freier-journalist\"><strong>Technik, Gesellschaft &amp; die Zukunft: Meine Arbeit als freier Journalist<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Neben meiner T\u00e4tigkeit als SEO-Berater bin ich ein Vollblutjournalist, der auf fast zwei Jahrzehnte Erfahrung zur\u00fcckblickt. Schon mit 17 Jahren begann ich als freiberuflicher Journalist regelm\u00e4\u00dfig Artikel und Reportagen f\u00fcr das \u00d6sterreichische Regionalblatt Kleine Zeitung beizusteuern. Seither ist es eine meiner gr\u00f6\u00dften Leidenschaften, spannende neue Themen zu erkunden und sie mit der Welt zu teilen. Als Reisejournalist hatte ich immer wieder Gelegenheit, Geschichten genau dort aufzugreifen, wo sie sich abspielen \u2013 ganz frei von Ber\u00fchrungs\u00e4ngsten. Heute schreibe ich regelm\u00e4\u00dfig Artikel zu den Bereichen Technologie, Gesellschaft und Umwelt f\u00fcr internationale Verleger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dieser Seite erfahren Sie mehr \u00fcber meine Arbeit als freier Journalist und k\u00f6nnen eine Auswahl meiner Artikel lesen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#artikel\"><strong>Zu den Artikeln<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"#gal\">Eindr\u00fccke von unterwegs<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"technik-einfach-ausgedruckt\">Wissenschaft und Technik, einfach ausgedr\u00fcckt.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine meiner St\u00e4rken als Journalist ist es, komplexe Zusammenh\u00e4nge in einfache Worte zu fassen. Diese F\u00e4higkeit ist vor allem dann besonders wichtig, wenn man \u00fcber Technologie und Wissenschaft schreibt. Ich liebe die Herausforderung, mich mit neuen, hochkomplexen Themen zu besch\u00e4ftigen, sie in einen verst\u00e4ndlichen Kontext zu setzen und auf eine Weise zu erkl\u00e4ren, die jeder verstehen kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Von k\u00fcnstlicher Intelligenz und der <a href=\"https:\/\/www.goethe.de\/ins\/ph\/de\/kul\/mag\/21121662.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Blockchain<\/strong><\/a>, zu Datenschutz im Internet und <a href=\"https:\/\/www.goethe.de\/ins\/be\/de\/kul\/prj\/nhk\/21621622.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>CO2-Kompensation<\/strong><\/a> \u2014 meine Artikel befassen sich stets mit aktuellen Themen. Sie sollen den Lesern dabei helfen, die Welt in der wir leben und die Zukunft, die uns erwartet, besser zu verstehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In meinem <a href=\"https:\/\/jczeller.com\/de\/blog\/\"><strong>SEO &amp; KI Blog<\/strong><\/a> teile ich mein Know-How \u00fcber Suchmaschinenoptimierung &amp; k\u00fcnstliche Intelligenz und stelle Do-It-Yourself Tutorials zur Verf\u00fcgung. Falls Sie interessiert sind, das Potenzial von KI f\u00fcr Ihr Unternehmen einzusetzen, dann stehe ich jetzt auch f\u00fcr <strong><a href=\"https:\/\/jczeller.com\/de\/ai-consultant\/\">KI-Beratung<\/a><\/strong> zur Verf\u00fcgung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"#kontakt\">Jetzt Kontakt aufnehmen<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"artikel\">Textproben: Artikel in verschiedenen Medien<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hier finden Sie einige Beispiele f\u00fcr meine Arbeit als freier Journalist. Unter anderem setzen sich die Artikel mit Themen wie k\u00fcnstlicher Intelligenz, Blockchain Technologie, Umweltschutz und Social Entrepreneurship auseinander. In meinem <strong><a href=\"https:\/\/jczeller.com\/de\/blog\/\">Blog<\/a> <\/strong>ver\u00f6ffentliche ich regelm\u00e4\u00dfig Updates zu meinen neuesten Beitr\u00e4gen, Ver\u00f6ffentlichungen und Vortr\u00e4gen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich hoffe, Sie genie\u00dfen die Lekt\u00fcre!<\/p>\n\n\n\n<center>\n<a href=\"https:\/\/www.wissenschaftskommunikation.de\/wie-spricht-man-ueber-ki-ohne-alarmismus-zu-befeuern-91167\/\" target=\"_blank\" title=\"Wie spricht man am besten \u00fcber KI Risiken?\" rel=\"noopener\">\n<h3>Wie spricht man am besten \u00fcber Risiken von KI?<\/h3><\/a>\n<i>Ein Beitrag zu den Risiken der k\u00fcnstlichen Intelligenz &#8211; und den Mythen, die den Diskurs pr\u00e4gen.<\/i>\n<br><br><a href=\"https:\/\/www.wissenschaftskommunikation.de\/wie-spricht-man-ueber-ki-ohne-alarmismus-zu-befeuern-91167\/\" target=\"_blank\" title=\"Wie spricht man am besten \u00fcber KI Risiken?\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/wk-ai.jpg\" alt=\"Wie spricht man am besten \u00fcber KI Risiken?\">\n<\/a>\n<br>\n[via <a href=\"https:\/\/www.wissenschaftskommunikation.de\/\" target=\"_blank\" title=\"Visit \"Wissenschaftskommunikation.de\" rel=\"noopener\">Wissenschaftskommunikation<\/a> \/\/ <a href=\"https:\/\/www.wissenschaftskommunikation.de\/wie-spricht-man-ueber-ki-ohne-alarmismus-zu-befeuern-91167\/\" target=\"_blank\" title=\"Wie spricht man am besten \u00fcber KI Risiken?\" rel=\"noopener\">Deutsch<\/a>]\n<br>\n<br>\n<br>\n<a href=\"https:\/\/skepticalinquirer.org\/exclusive\/the-german-dilemma-continues-skepticism-in-the-face-of-ideological-conflict\/\" target=\"_blank\" title=\"The German Dilemma Continues\" rel=\"noopener\">\n<h3>Das deutsche Dilemma geht weiter<\/h3><\/a>\n<i>Der zweite Teil meiner Artikelserie zum Konflikt in der GWUP.<\/i>\n<br><br><a href=\"https:\/\/skepticalinquirer.org\/exclusive\/the-german-dilemma-continues-skepticism-in-the-face-of-ideological-conflict\/\" target=\"_blank\" title=\"The German Dilemma Continues\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/si-dl2.jpg\" alt=\"The German Dilemma Continues\">\n<\/a>\n<br>\n[via <a href=\"https:\/\/skepticalinquirer.org\/\" target=\"_blank\" title=\"Besuchen Sie den Skeptical Inquirer\" rel=\"noopener\">Skeptical Inquirer<\/a> &#038; <a href=\"https:\/\/de.richarddawkins.net\" target=\"_blank\" title=\"Besuchen Sie die RDF\" rel=\"noopener\">Richard Dawkins Foundation f\u00fcr Vernunft &#038; Wissenschaft<\/a> \/\/ <a href=\"https:\/\/de.richarddawkins.net\/articles\/das-deutsche-dilemma-geht-weiter\" target=\"_blank\" title=\"Das deutsche Dilemma geht weiter\" rel=\"noopener\">Deutsch<\/a> | <a href=\"https:\/\/skepticalinquirer.org\/exclusive\/the-german-dilemma-continues-skepticism-in-the-face-of-ideological-conflict\/\" target=\"_blank\" title=\"The German Dilemma\" rel=\"noopener\">Englisch<\/a>]\n<br>\n<br>\n<br>\n\n<a href=\"https:\/\/skepticalinquirer.org\/exclusive\/the-german-dilemma-a-skeptic-schism-with-global-implications\/\" target=\"_blank\" title=\"The German Dilemma\" rel=\"noopener\">\n<h3>Wie &#8218;Woke&#8216;-Themen Skeptiker spalten<\/h3><\/a>\n<i>Eine Analyse der aktuellen F\u00fchrungskrise bei der deutschen GWUP und die Implikationen f\u00fcr Skeptiker rund um die Welt.<\/i>\n<br><br><a href=\"https:\/\/skepticalinquirer.org\/exclusive\/the-german-dilemma-a-skeptic-schism-with-global-implications\/\" target=\"_blank\" title=\"The German Dilemma\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/si-gwup.jpg\" alt=\"The German Dilemma\">\n<\/a>\n<br>\n[via <a href=\"https:\/\/skepticalinquirer.org\/\" target=\"_blank\" title=\"Besuchen Sie den Skeptical Inquirer\" rel=\"noopener\">Skeptical Inquirer<\/a> &#038; <a href=\"https:\/\/de.richarddawkins.net\" target=\"_blank\" title=\"Besuchen Sie die RDF\" rel=\"noopener\">Richard Dawkins Foundation f\u00fcr Vernunft &#038; Wissenschaft<\/a> \/\/ <a href=\"https:\/\/de.richarddawkins.net\/articles\/eine-skeptische-spaltung-mit-globalen-auswirkungen\" target=\"_blank\" title=\"Das deutsche Dilemma\" rel=\"noopener\">Deutsch<\/a> | <a href=\"https:\/\/skepticalinquirer.org\/exclusive\/the-german-dilemma-a-skeptic-schism-with-global-implications\/\" target=\"_blank\" title=\"The German Dilemma\" rel=\"noopener\">Englisch<\/a>]\n<br>\n<br>\n<br>\n<a href=\"https:\/\/www.goethe.de\/prj\/geg\/de\/24976995.html\" target=\"_blank\" title=\"Geschichte &#038; Zukunft des Internets\" rel=\"noopener\">\n<h3>Wie wird das Internet der Zukunft aussehen?<\/h3><\/a>\n<i>Ein Gespr\u00e4ch mit Michael Rotert \u00fcber die Geschichte und Zukunft des gr\u00f6\u00dften Netzwerks der Menschheit.<\/i>\n<br><br><a href=\"https:\/\/www.goethe.de\/prj\/geg\/de\/24976995.html\" target=\"_blank\" title=\"Interview Michael Rotert\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe-inet-de.jpg\" alt=\"Interview Michael Rotert\">\n<\/a>\n<br>\n[via <a href=\"https:\/\/www.goethe.de\/\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a> \/\/ <a href=\"https:\/\/www.goethe.de\/prj\/geg\/en\/24976995.html\" target=\"_blank\" title=\"Interview Michael Rotert\" rel=\"noopener\">Englisch<\/a>\n| <a href=\"https:\/\/www.goethe.de\/prj\/geg\/de\/24976995.html\" target=\"_blank\" title=\"Interview Michael Rotert\" rel=\"noopener\">Deutsch<\/a>]\n<br>\n<br>\n<br>\n<a href=\"https:\/\/www.goethe.de\/prj\/zei\/de\/pdk\/24525775.html\" target=\"_blank\" title=\"Interview Michael Seemann\" rel=\"noopener\">\n<h3>Wie beeinflusst Social Media die \u00f6ffentliche Meinung?<\/h3><\/a>\n<i>Kulturwissenschaftler Michael Seeman spricht \u00fcber die Macht der sozialen Netzwerke, die Twitter Files und Elon Musk.<\/i>\n<br><br><a href=\"https:\/\/www.goethe.de\/prj\/zei\/de\/pdk\/24525775.html\" target=\"_blank\" title=\"Interview Michael Seemann\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/zeitgeister-sm-de.jpg\" alt=\"Interview Michael Seemann\">\n<\/a>\n<br>\n[via <a href=\"https:\/\/www.goethe.de\/prj\/zei\/de\/index.html\" target=\"_blank\" title=\"Besuchen Sie Zeitgeister\" rel=\"noopener\">Zeitgeister<\/a> \/\/ <a href=\"https:\/\/www.goethe.de\/prj\/zei\/en\/pdk\/24525775.html\" target=\"_blank\" title=\"Interview Michael Seemann\" rel=\"noopener\">Englisch<\/a>\n| <a href=\"https:\/\/www.goethe.de\/prj\/zei\/de\/pdk\/24525775.html\" target=\"_blank\" title=\"Interview Michael Seemann\" rel=\"noopener\">Deutsch<\/a>]\n<br>\n<br>\n<br>\n<a href=\"https:\/\/www.goethe.de\/prj\/lqs\/de\/art\/cqc.html\" target=\"_blank\" title=\"Interview Emily Haworth\" rel=\"noopener\">\n<h3>K\u00f6nnte ein Quantensprung das Klima retten?<\/h3><\/a>\n<i>Interview mit der Quantenexpertin Emily Haworth.<\/i>\n<br><br><a href=\"https:\/\/www.goethe.de\/prj\/lqs\/de\/art\/cqc.html\" target=\"_blank\" title=\"Interview Emily Haworth\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/preview-qi.jpg\" alt=\"Interview Emily Haworth\">\n<\/a>\n<br>\n[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a> &#038; <a href=\"https:\/\/thequantuminsider.com\" target=\"_blank\" title=\"Besuchen Sie The Quantum Insider\" rel=\"noopener\">The Quantum Insider<\/a>\n\/\/ <a href=\"https:\/\/thequantuminsider.com\/2022\/10\/27\/could-quantum-computers-save-the-climate\/\" target=\"_blank\" title=\"Interview Emily Haworth\" rel=\"noopener\">Englisch<\/a>\n| <a href=\"https:\/\/www.goethe.de\/prj\/lqs\/de\/art\/cqc.html\" target=\"_blank\" title=\"Interview Emily Haworth\" rel=\"noopener\">Deutsch<\/a>]\n<br>\n<br>\n<br>\n\n\n\n<a href=\"https:\/\/www.goethe.de\/prj\/zei\/de\/pdk\/22701757.html\" target=\"_blank\" title=\"Interview Maureen Webb\" rel=\"noopener\">\n<h3>Demokratie im digitalen Raum<\/h3><\/a>\n<i>Ein Gespr\u00e4ch mit Menschenrechtsjuristin Maureen Webb \u00fcber diskriminierende Technologien und digitale Grundrechte.<\/i>\n<br><br><a href=\"https:\/\/www.goethe.de\/prj\/zei\/de\/pdk\/22701757.html\" target=\"_blank\" title=\"Interview Maureen Webb\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe-maureen_de.jpg\" alt=\"Interview Maureen Webb\">\n<\/a>\n<br>\n[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a>\n\/\/ <a href=\"https:\/\/www.goethe.de\/prj\/zei\/en\/pdk\/22701757.html\" target=\"_blank\" title=\"Interview Maureen Webb\" rel=\"noopener\">Englisch<\/a>\n| <a href=\"https:\/\/www.goethe.de\/prj\/zei\/de\/pdk\/22701757.html\" target=\"_blank\" title=\"Interview Maureen Webb\" rel=\"noopener\">Deutsch<\/a>]\n<br>\n<br>\n<br>\n<a href=\"https:\/\/www.goethe.de\/ins\/es\/de\/kul\/mag\/22406095.html\" target=\"_blank\" title=\"Transformation der St\u00e4dte\" rel=\"noopener\">\n<h3>Urbane Kunst transformiert St\u00e4dte<\/h3><\/a>\n<i>Kunst im urbanen Raum als Element sozialen Wandels.<\/i>\n<br><a href=\"https:\/\/www.goethe.de\/ins\/es\/de\/kul\/mag\/22406095.html\" target=\"_blank\" title=\"Urban Art\" rel=\"noopener\">\n<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe-urban-art21_de.jpg\" alt=\"Urban Art\">\n<\/a>\n<br>\n[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a>\n\/\/ <a href=\"https:\/\/www.goethe.de\/ins\/us\/en\/kul\/art\/22406095.html\" target=\"_blank\" title=\"Urban Art\" rel=\"noopener\">Englisch<\/a>\n| <a href=\"https:\/\/www.goethe.de\/ins\/es\/de\/kul\/mag\/22406095.html\" target=\"_blank\" title=\"Urban Art\" rel=\"noopener\">Deutsch<\/a>]\n<br>\n<br>\n<br>\n\n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/us\/de\/kul\/tec\/22155868.html\" target=\"_blank\" title=\"Interview Markus Beckedahl\" rel=\"noopener\">\n\t\t<h3>Digitale Selbstverteidigung<\/h3><\/a>\n<i>In diesem Interview gibt Markus Beckedahl Expertentipps f\u00fcr mehr Sicherheit und Datenschutz im Internet.<\/i>\n\t\t<br><a href=\"https:\/\/www.goethe.de\/ins\/us\/de\/kul\/tec\/22155868.html\" target=\"_blank\" title=\"Interview Markus Beckedahl\" rel=\"noopener\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe-digital-defence_de.jpg\" alt=\"Interview Markus Beckedahl\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a>\n\t\t\/\/ <a href=\"https:\/\/www.goethe.de\/ins\/us\/en\/kul\/tec\/22155868.html\" target=\"_blank\" title=\"Interview Markus Beckedahl\" rel=\"noopener\">Englisch<\/a>\n\t\t| <a href=\"https:\/\/www.goethe.de\/ins\/us\/de\/kul\/tec\/22155868.html\" target=\"_blank\" title=\"Interview Markus Beckedahl\" rel=\"noopener\">Deutsch<\/a>]\n\t\t<br>\n\t\t<br>\n\t\t<br>\n\n\n<a href=\"https:\/\/www.goethe.de\/ins\/ts\/de\/kul\/mag\/21674003.html\" target=\"_blank\" title=\"Wie l\u00e4sst sich Plastikm\u00fcll vermeiden?\" rel=\"noopener\">\n\t\t<h3>Eine Welt ohne Plastik<\/h3><\/a>\n<i>7 Initiativen rund um die Welt, um Abfall zu vermeiden. <\/i>\n\t\t<br><a href=\"https:\/\/www.goethe.de\/ins\/ts\/de\/kul\/mag\/21674003.html\" target=\"_blank\" title=\"Stoppt Plastikm\u00fcll!\" rel=\"noopener\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe-noplastic_de.jpg\" alt=\"Plastik verschmutzt die Meere\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a>\n\t\t\/\/ <a href=\"https:\/\/www.goethe.de\/ins\/ts\/en\/kul\/mag\/21674003.html\" target=\"_blank\" title=\"Plastic waste reduction\" rel=\"noopener\">Englisch<\/a>\n\t\t| <a href=\"https:\/\/www.goethe.de\/ins\/ts\/de\/kul\/mag\/21674003.html\" target=\"_blank\" title=\"Weniger Plastikm\u00fcll?\" rel=\"noopener\">Deutsch<\/a>]\n\t\t<br>\n\t\t<br>\n\t\t<br>\n\t\n\t\t\n\t\t<a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-07\/issue07\/issue07\/whistleblowers-are-the-guardians-of-our-rights\/\" target=\"_blank\" title=\"Interview Vladimir Radomirovic\" rel=\"noopener\">\n\t\t<h3>\u201cWhistleblowers are the guardians of our rights\u201d<\/h3><\/a>\n<i>Interview mit Vladimir Radomirovic vom serbischen Whistleblower-Portal Pi\u0161taljka.<\/i><br>(Nur auf Englisch verf\u00fcgbar)\n\t\t<br>\n\t\t<a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-07\/issue07\/issue07\/whistleblowers-are-the-guardians-of-our-rights\/\" target=\"_blank\" title=\"Interview Vladimir Radomirovic\" rel=\"noopener\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/tat-whistleblowers.jpg\" alt=\"Whistleblowers\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/tea-after-twelve.com\/\" target=\"_blank\" title=\"it's tea time ;)\" rel=\"noopener\">Tea After Twelve<\/a> \/\/ <a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-07\/issue07\/issue07\/whistleblowers-are-the-guardians-of-our-rights\/\" target=\"_blank\" title=\"Interview Vladimir Radomirovic\" rel=\"noopener\">Englisch<\/a>]\n\t\t<br>\n\t\t<br>\n\t\t<br>\n\n\t\t\n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/gb\/de\/kul\/zut\/rob\/21481185.html\" target=\"_blank\" title=\"Humanoide Roboter\" rel=\"noopener\">\n\t\t<h3>Wann kommt der &#8218;menschliche&#8216; Roboter?<\/h3><\/a>\n<i>Einblicke in die letzten Entwicklungen auf dem Gebiet der k\u00fcnstlichen Intelligenz.<\/i>\n\t\t<br><a href=\"https:\/\/www.goethe.de\/ins\/gb\/de\/kul\/zut\/rob\/21481185.html\" target=\"_blank\" title=\"Der menschliche Roboter\" rel=\"noopener\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe-robots_de.jpg\" alt=\"Roboter\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a>\n\t\t\/\/ <a href=\"https:\/\/www.goethe.de\/ins\/gb\/en\/kul\/zut\/rob\/21481185.html\" target=\"_blank\" title=\"Human Robots\" rel=\"noopener\">Englisch<\/a>\n\t\t| <a href=\"https:\/\/www.goethe.de\/ins\/gb\/de\/kul\/zut\/rob\/21481185.html\" target=\"_blank\" title=\"Menschliche Roboter\" rel=\"noopener\">Deutsch<\/a>]\n\t\t<br>\n\t\t<br>\n\t\t<br>\n\n\n\n<a href=\"https:\/\/www.goethe.de\/ins\/gb\/de\/kul\/mag\/21506369.html\" target=\"_blank\" title=\"Die Zukunft von KI\" rel=\"noopener\">\n\t\t<h3>Der einf\u00fchlsame Algorithmus<\/b><\/h3><\/a>\n<i>K\u00f6nnte k\u00fcnstliche Intelligenz uns eines Tages zur Unsterblichkeit verhelfen?<\/i>\n\t\t<br><a href=\"https:\/\/www.goethe.de\/ins\/gb\/de\/kul\/mag\/21506369.html\" target=\"_blank\" title=\"K\u00fcnstliche Intelligenz\" rel=\"noopener\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe_ai2.jpg\" alt=\"Algorithmen &#038; die Zukunft\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a> \/\/ \n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/gb\/en\/kul\/mag\/21506369.html\" target=\"_blank\" title=\"Algorithms\" rel=\"noopener\">Englisch<\/a>\n\t\t| <a href=\"https:\/\/www.goethe.de\/ins\/gb\/de\/kul\/mag\/21506369.html\" target=\"_blank\" title=\"Der einf\u00fchlsame Algorithmus\" rel=\"noopener\">Deutsch<\/a>]\n\t\t<br>\n\t\t<br>\n\t\t<br>\n\t\t\n\t\t<a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-05\/issue-05\/chapter-1\/paint-thicker-than-blood\/\" target=\"_blank\" title=\"Article \u00fcber Graffiti in Bogot\u00e1\" rel=\"noopener\">\n\t\t<h3>Paint Thicker Than Blood<\/h3><\/a>\n<i>Graffiti als Medium der Ver\u00e4nderung: Ein Spaziergang durch Bogot\u00e1s Stadtteil Fontib\u00f3n mit Stra\u00dfenk\u00fcnstlicher Mos Ku.<\/i><br>(Nur auf Englisch verf\u00fcgbar)\n\t\t<br>\n\t\t<a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-05\/issue-05\/chapter-1\/paint-thicker-than-blood\/\" target=\"_blank\" title=\"Graffiti in Bogot\u00e1\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/tat_graffiti.jpg\" alt=\"Mos Ku Tattoo Artist\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/tea-after-twelve.com\/\" target=\"_blank\" title=\"it's tea time ;)\" rel=\"noopener\">Tea After Twelve<\/a> \/\/ <a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-05\/issue-05\/chapter-1\/paint-thicker-than-blood\/\" target=\"_blank\" title=\"Article on Graffiti in Bogot\u00e1\" rel=\"noopener\">English<\/a>]\n\t\t<br>\n\t\t<br>\n\t\t<br>\n\n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/ph\/de\/kul\/mag\/21121662.html\" target=\"_blank\" title=\"Blockchain verstehen\" rel=\"noopener\">\n\t\t<h3>Blockchain: Die Kette ohne schwaches Glied<\/h3><\/a>\n<i>Was ist eine Blockchain und wie wird sich die Technologie auf unseren Alltag auswirken?<\/i>\n\t\t<br>\n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/ph\/de\/kul\/mag\/21121662.html\" target=\"_blank\" title=\"Erkl\u00e4rung Blockchain\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe_blockchain.jpg\" alt=\"Blockchain Technology\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a> \/\/ \n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/ph\/en\/kul\/mag\/21121662.html\" target=\"_blank\" title=\"Article on Blockchain Technology\" rel=\"noopener\">Englisch<\/a> |\n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/ph\/de\/kul\/mag\/21121662.html\" target=\"_blank\" title=\"Die Kette ohne schwaches Glied\" rel=\"noopener\">Deutsch<\/a>]\n\t\t<br>\n\t\t\n\t\n\t\t\n\t\t<br>\n\t\t<br>\n\t\t<a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-02\/issue-02-overview\/chapter1\/dreams-rewired\/\" target=\"_blank\" title=\"Review on Dreams Rewired\" rel=\"noopener\">\n\t\t<h3>Dreams Rewired &#8211; Every Age Thinks It&#8217;s the Modern Age<\/h3><\/a>\n<i>Die Regisseure Manu Luksch &#038; Martin Reinhart sprechen \u00fcber ihr gleicherma\u00dfen technophobes wie technophiles Meisterwerk \u201eDreams Rewired\u201c.<\/i>\n<br>\n(Nur auf Englisch verf\u00fcgbar)\n\t\t<br><a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-02\/issue-02-overview\/chapter1\/dreams-rewired\/\" target=\"_blank\" title=\"Review on Dreams Rewired\" rel=\"noopener\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/tat_dreams.jpg\" alt=\"Dreams Rewired - Every Age Thinks It's the Modern Age\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/tea-after-twelve.com\/\" target=\"_blank\" title=\"it's tea time ;)\" rel=\"noopener\">Tea After Twelve<\/a> \/\/ <a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-02\/issue-02-overview\/chapter1\/dreams-rewired\/\" target=\"_blank\" title=\"Dreams Rewired - Every Age Thinks It's the Modern Age\" rel=\"noopener\">Englisch<\/a>]\n\t\t<br>\n\t\t<br>\n\t\t<br>\n\n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/us\/de\/kul\/mag\/21135394.html\" target=\"_blank\" title=\"Trikont independent Label\" rel=\"noopener\">\n\t\t<h3>Rebellion auf Bayrisch<\/h3><\/a>\n<i>Ein Artikel zu Ehren des Trikont Musiklabels und von Achim Bergmann, der leider kurz nach der Ver\u00f6ffentlichung verstorben ist.<\/i>\n\t\t<br><a href=\"https:\/\/www.goethe.de\/ins\/us\/de\/kul\/mag\/21135394.html\" target=\"_blank\" title=\"50 Jahre Trikont\" rel=\"noopener\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/goethe_trikont.jpg\" alt=\"Das Trikont Label\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/goethe.de\" target=\"_blank\" title=\"Besuchen Sie das Goethe Institut\" rel=\"noopener\">Goethe.de<\/a> \/\/ \n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/us\/en\/kul\/mag\/21135394.html\" target=\"_blank\" title=\"Article on the Trikont independent label\" rel=\"noopener\">Englisch<\/a> | \n\t\t<a href=\"https:\/\/www.goethe.de\/ins\/us\/de\/kul\/mag\/21135394.html\" target=\"_blank\" title=\"Rebellion auf Bayerisch\" rel=\"noopener\">Deutsch<\/a>]\n\t\t<br>\n\t\t<br>\n\t\t<br>\n\n\n<a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-04\/issue-04\/chapter-2\/misfit-economy\/\" target=\"_blank\" title=\"The Misfit Economy\" rel=\"noopener\">\n\t\t<h3>&#8218;The Misfit Economy&#8216; &#8211; Business-Advice from Pirates and Gangsters<\/h3><\/a>\n<i>Entdecken Sie wirtschaftliche Kreativit\u00e4t in H\u00f6chstform in dieser ausf\u00fchrlichen Rezension von Alexa Clays und Kayra Phillips erfrischendem Buch \u201eThe Misfit Economy\u201c.<\/i>\n<br>(Nur auf Englisch verf\u00fcgbar)\n\t\t<br><a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-04\/issue-04\/chapter-2\/misfit-economy\/\" target=\"_blank\" title=\"Review on The Misfit Economy\" rel=\"noopener\">\n\t\t<img decoding=\"async\" src=\"https:\/\/jczeller.com\/pics\/previews\/tat_misfit.jpg\" alt=\"Lesetipp: The Misfit Economy\">\n\t\t<\/a>\n\t\t<br>\n\t\t[via <a href=\"http:\/\/tea-after-twelve.com\/\" target=\"_blank\" title=\"it's tea time ;)\" rel=\"noopener\">Tea After Twelve<\/a> \/\/ <a href=\"http:\/\/www.tea-after-twelve.com\/all-issues\/issue-04\/issue-04\/chapter-2\/misfit-economy\/\" target=\"_blank\" title=\"Review on The Misfit Economy\" rel=\"noopener\">English<\/a>]\n\t\t<\/center>\n\n\n\n<div class=\"wp-block-group alignfull has-black-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color\" id=\"gal\"><strong>Ein paar Eindr\u00fccke von unterwegs<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><font color=\"#ffffff\">Hier finden Sie einige Bilder und Erinnerungen von meinen journalistischen Entdeckungsreisen \ud83d\ude42<\/font><\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/climbing-suesca.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" data-id=\"89\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/climbing-suesca-1024x680.jpg\" alt=\"Climber's El Dorado Suesca\" class=\"wp-image-89\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/climbing-suesca-1024x680.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/climbing-suesca-300x199.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/climbing-suesca-768x510.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/climbing-suesca-1536x1021.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/climbing-suesca.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Climber&#8217;s El Dorado Suesca<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/cultiva-peyote.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" data-id=\"90\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/cultiva-peyote-1024x680.jpg\" alt=\"Cultiva Hanf Messe\" class=\"wp-image-90\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/cultiva-peyote-1024x680.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/cultiva-peyote-300x199.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/cultiva-peyote-768x510.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/cultiva-peyote-1536x1021.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/cultiva-peyote.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Cultiva Hanf Messe<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/green-place-bogota.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"670\" data-id=\"97\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/green-place-bogota-1024x670.jpg\" alt=\"Einer der letzten gr\u00fcnen Flecken in einer 9-Millionen Stadt.\" class=\"wp-image-97\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/green-place-bogota-1024x670.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/green-place-bogota-300x196.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/green-place-bogota-768x502.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/green-place-bogota-1536x1004.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/green-place-bogota.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Einer der letzten gr\u00fcnen Flecken in einer 9-Millionen Stadt.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/doggos.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"91\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/doggos-1024x768.jpg\" alt=\"Making new friends on the road\" class=\"wp-image-91\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/doggos-1024x768.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/doggos-300x225.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/doggos-768x576.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/doggos-1536x1152.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/doggos.jpg 1559w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Making new friends on the road<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/east-coast-memorial.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"93\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/east-coast-memorial-1024x768.jpg\" alt=\"At the East Coast Memorial\" class=\"wp-image-93\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/east-coast-memorial-1024x768.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/east-coast-memorial-300x225.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/east-coast-memorial-768x576.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/east-coast-memorial-1536x1152.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/east-coast-memorial.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">At the East Coast Memorial<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"488\" data-id=\"95\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota-1024x488.jpg\" alt=\"Mural-Galerie in Bogot\u00e1's\" class=\"wp-image-95\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota-1024x488.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota-300x143.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota-768x366.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota-1536x732.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota-2048x976.jpg 2048w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota-2000x953.jpg 2000w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/graffiti-bogota-1800x857.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Mural-Galerie in Bogot\u00e1s<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/gmf.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"94\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/gmf-1024x576.jpg\" alt=\"Global Media Forum in Bonn\" class=\"wp-image-94\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/gmf-1024x576.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/gmf-300x169.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/gmf-768x432.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/gmf-1536x864.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/gmf-1800x1013.jpg 1800w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/gmf.jpg 1900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Global Media Forum in Bonn<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/great-barrier-reef.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"96\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/great-barrier-reef-1024x683.jpg\" alt=\"Erkundung der Fauna im Great Barrier Reef\" class=\"wp-image-96\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/great-barrier-reef-1024x683.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/great-barrier-reef-300x200.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/great-barrier-reef-768x512.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/great-barrier-reef-1536x1024.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/great-barrier-reef.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Erkundung der Fauna im Great Barrier Reef<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/jungle-friends.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"98\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/jungle-friends-1024x768.jpg\" alt=\"Neue Bekanntschaften im Regenwald\" class=\"wp-image-98\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/jungle-friends-1024x768.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/jungle-friends-300x225.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/jungle-friends-768x576.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/jungle-friends-1536x1151.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/jungle-friends.jpg 1569w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Neue Bekanntschaften im Regenwald<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"701\" height=\"1024\" data-id=\"101\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin02-701x1024.jpg\" alt=\"MardiGrass Festival in Nimbin, Australien. Bildrechte: Leon Wittig.\" class=\"wp-image-101\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin02-701x1024.jpg 701w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin02-205x300.jpg 205w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin02-768x1121.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin02-1052x1536.jpg 1052w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin02.jpg 1200w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><\/a><figcaption class=\"wp-element-caption\">MardiGrass Festival in Nimbin, Australien. Bildrechte: Leon Wittig.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin01.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"752\" data-id=\"100\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin01-1024x752.jpg\" alt=\"Bildrechte: Leon Wittig.\" class=\"wp-image-100\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin01-1024x752.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin01-300x220.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin01-768x564.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin01-1536x1128.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin01.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Bildrechte: Leon Wittig.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin03.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"689\" data-id=\"102\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin03-1024x689.jpg\" alt=\"Bildrechte: Leon Wittig.\" class=\"wp-image-102\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin03-1024x689.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin03-300x202.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin03-768x517.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin03-1536x1033.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/nimbin03.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Bildrechte: Leon Wittig.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/druiden-johanna.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"92\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/druiden-johanna-1024x683.jpg\" alt=\"Auf Besuch bei den Druiden (Photo credit: Johanna Lea Lassnig)\" class=\"wp-image-92\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/druiden-johanna-1024x683.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/druiden-johanna-300x200.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/druiden-johanna-768x512.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/druiden-johanna-1536x1024.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/druiden-johanna.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Auf Besuch bei den Druiden. Bildrechte: <a href=\"https:\/\/www.instagram.com\/johannalealassnig\/\" title=\"Mehr von Johanna\" target=\"_blank\" rel=\"noopener\"><b>Johanna Lea Lassnig<\/b><\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/rio-claro.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"104\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/rio-claro-768x1024.jpg\" alt=\"Rio Claro \u2665\" class=\"wp-image-104\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/rio-claro-768x1024.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/rio-claro-225x300.jpg 225w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/rio-claro-1152x1536.jpg 1152w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/rio-claro.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\">Rio Claro \u2665<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/on-the-road.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"716\" data-id=\"103\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/on-the-road-1024x716.jpg\" alt=\"Always happy on the road ;-)\" class=\"wp-image-103\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/on-the-road-1024x716.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/on-the-road-300x210.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/on-the-road-768x537.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/on-the-road-1536x1073.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/on-the-road.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Always happy on the road \ud83d\ude09<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/tattoo-convention.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"105\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/tattoo-convention-768x1024.jpg\" alt=\"Just another Tattoo convention\" class=\"wp-image-105\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/tattoo-convention-768x1024.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/tattoo-convention-225x300.jpg 225w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/tattoo-convention-1152x1536.jpg 1152w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/tattoo-convention.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption class=\"wp-element-caption\">Just another Tattoo convention<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/the-great-outdoors.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" data-id=\"106\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/the-great-outdoors-1024x680.jpg\" alt=\"Outdoor-Expedition\" class=\"wp-image-106\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/the-great-outdoors-1024x680.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/the-great-outdoors-300x199.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/the-great-outdoors-768x510.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/the-great-outdoors-1536x1021.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/the-great-outdoors.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Outdoor-Expedition in \u00d6sterreich<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/la-estancia.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"99\" src=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/la-estancia-1024x683.jpg\" alt=\"Getting ready for the road in Colombia\" class=\"wp-image-99\" srcset=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/la-estancia-1024x683.jpg 1024w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/la-estancia-300x200.jpg 300w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/la-estancia-768x512.jpg 768w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/la-estancia-1536x1024.jpg 1536w, https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/la-estancia.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Getting ready for the road in Colombia<\/figcaption><\/figure>\n<\/figure>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"kontakt\">W\u00fcnsche, Fragen, Anregungen?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Falls Sie Fragen oder Anmerkungen zu meinen Texten haben, k\u00f6nnen Sie sich gerne an mich wenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nutzen Sie daf\u00fcr bitte das Kontaktformular:<\/p>\n\n\n<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-2bb0e77b-cafa-4ce2-a78a-583167c492cd\" id=\"wpforms-37\"><form id=\"wpforms-form-37\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"37\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/80\" data-token=\"e86b6f26755d5ea63f52e23e5a23eb70\" data-token-time=\"1784083286\"><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-37-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-37-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-37-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" required><\/div><div id=\"wpforms-37-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-37-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-37-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-37-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-37-field_2\">Ihre Nachricht <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-37-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><div id=\"wpforms-37-field_3-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"3\"><label class=\"wpforms-field-label\">Datenschutzerkl\u00e4rung <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-37-field_3\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-37-field_3_1\" name=\"wpforms[fields][3][]\" value=\"Ich akzeptiere die Datenschutzerkl\u00e4rung\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-37-field_3_1\">Ich akzeptiere die Datenschutzerkl\u00e4rung<\/label><\/li><\/ul><div class=\"wpforms-field-description wpforms-disclaimer-description\"><a href=\"https:\/\/jczeller.com\/de\/datenschutz\/\" title=\"Datenschutz\">Lesen Sie die Datenschutzerkl\u00e4rung hier.<\/a><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-hcaptcha\" ><div class=\"h-captcha\" data-sitekey=\"e9d27d40-23b8-4e40-9334-a31c51461868\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-hcaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"37\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/pages\/80\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-37\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jczeller.com\/de\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div><input\n                    class=\"apbct_special_field apbct_email_id__wp_wpforms\"\n                    name=\"apbct__email_id__wp_wpforms\"\n                    aria-label=\"apbct__label_id__wp_wpforms\"\n                    type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n                    value=\"\"\n                \/><\/form><\/div>  <!-- .wpforms-container -->\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">K\u00fcnstler Titelbild: <a href=\"https:\/\/instagram.com\/moskuuu\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Mos Ku<\/strong><\/a> &#8211; Much\u00edsimas gracias \ud83d\ude42<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Technik, Gesellschaft &amp; die Zukunft: Meine Arbeit als freier Journalist Neben meiner T\u00e4tigkeit als SEO-Berater bin ich ein Vollblutjournalist, der auf fast zwei Jahrzehnte Erfahrung zur\u00fcckblickt. Schon mit 17 Jahren begann ich als freiberuflicher Journalist regelm\u00e4\u00dfig Artikel und Reportagen f\u00fcr das \u00d6sterreichische Regionalblatt Kleine Zeitung beizusteuern. Seither ist es eine meiner gr\u00f6\u00dften Leidenschaften, spannende neue &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/jczeller.com\/de\/journalismus\/\" class=\"more-link\">Mehr <span class=\"screen-reader-text\">\u00fcber &#8222;Journalismus&#8220; <\/span>Lesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":81,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inspiro_hide_title":false,"inspiro_hide_featured_image":false,"footnotes":""},"class_list":["post-80","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feier Journalismus \u00fcber Technik, Gesellschaft &amp; die Zukunft<\/title>\n<meta name=\"description\" content=\"Als freier Journalist schreibe ich seit \u00fcber 2 Jahrzehnten \u00fcber den Einfluss von Technologie auf die Gesellschaft. Lesen Sie mehr!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jczeller.com\/de\/journalismus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technologie, Gesellschaft &amp; die Zukunft: Freier Journalismus\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie mehr \u00fcber meine Arbeit als freier Journalist und lesen Sie die neuesten Artikel!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jczeller.com\/de\/journalismus\/\" \/>\n<meta property=\"og:site_name\" content=\"Ihr SEO-Berater und Copywriter.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-23T11:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/journalism-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1932\" \/>\n\t<meta property=\"og:image:height\" content=\"1403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Technologie, Gesellschaft &amp; die Zukunft: Freier Journalismus\" \/>\n<meta name=\"twitter:description\" content=\"Erfahren Sie mehr \u00fcber meine Arbeit als freier Journalist und lesen Sie die neuesten Artikel!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/journalism-header.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/journalismus\\\/\",\"url\":\"https:\\\/\\\/jczeller.com\\\/de\\\/journalismus\\\/\",\"name\":\"Feier Journalismus \u00fcber Technik, Gesellschaft & die Zukunft\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/journalismus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/journalismus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jczeller.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/journalism-header.jpg\",\"datePublished\":\"2021-09-16T14:31:17+00:00\",\"dateModified\":\"2025-09-23T11:11:01+00:00\",\"description\":\"Als freier Journalist schreibe ich seit \u00fcber 2 Jahrzehnten \u00fcber den Einfluss von Technologie auf die Gesellschaft. Lesen Sie mehr!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/journalismus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jczeller.com\\\/de\\\/journalismus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/journalismus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jczeller.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/journalism-header.jpg\",\"contentUrl\":\"https:\\\/\\\/jczeller.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/journalism-header.jpg\",\"width\":1932,\"height\":1403,\"caption\":\"Freier Journalismus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/journalismus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/jczeller.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journalismus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/jczeller.com\\\/de\\\/\",\"name\":\"Ihr SEO-Berater und Copywriter.\",\"description\":\"Kreativit\u00e4t trifft Expertise\",\"publisher\":{\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jczeller.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/#organization\",\"name\":\"Ihr SEO-Berater und Copywriter.\",\"url\":\"https:\\\/\\\/jczeller.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jczeller.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-jcz-trans3.png\",\"contentUrl\":\"https:\\\/\\\/jczeller.com\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-jcz-trans3.png\",\"width\":561,\"height\":881,\"caption\":\"Ihr SEO-Berater und Copywriter.\"},\"image\":{\"@id\":\"https:\\\/\\\/jczeller.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feier Journalismus \u00fcber Technik, Gesellschaft & die Zukunft","description":"Als freier Journalist schreibe ich seit \u00fcber 2 Jahrzehnten \u00fcber den Einfluss von Technologie auf die Gesellschaft. Lesen Sie mehr!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jczeller.com\/de\/journalismus\/","og_locale":"de_DE","og_type":"article","og_title":"Technologie, Gesellschaft & die Zukunft: Freier Journalismus","og_description":"Erfahren Sie mehr \u00fcber meine Arbeit als freier Journalist und lesen Sie die neuesten Artikel!","og_url":"https:\/\/jczeller.com\/de\/journalismus\/","og_site_name":"Ihr SEO-Berater und Copywriter.","article_modified_time":"2025-09-23T11:11:01+00:00","og_image":[{"width":1932,"height":1403,"url":"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/journalism-header.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Technologie, Gesellschaft & die Zukunft: Freier Journalismus","twitter_description":"Erfahren Sie mehr \u00fcber meine Arbeit als freier Journalist und lesen Sie die neuesten Artikel!","twitter_image":"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/journalism-header.jpg","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jczeller.com\/de\/journalismus\/","url":"https:\/\/jczeller.com\/de\/journalismus\/","name":"Feier Journalismus \u00fcber Technik, Gesellschaft & die Zukunft","isPartOf":{"@id":"https:\/\/jczeller.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jczeller.com\/de\/journalismus\/#primaryimage"},"image":{"@id":"https:\/\/jczeller.com\/de\/journalismus\/#primaryimage"},"thumbnailUrl":"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/journalism-header.jpg","datePublished":"2021-09-16T14:31:17+00:00","dateModified":"2025-09-23T11:11:01+00:00","description":"Als freier Journalist schreibe ich seit \u00fcber 2 Jahrzehnten \u00fcber den Einfluss von Technologie auf die Gesellschaft. Lesen Sie mehr!","breadcrumb":{"@id":"https:\/\/jczeller.com\/de\/journalismus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jczeller.com\/de\/journalismus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jczeller.com\/de\/journalismus\/#primaryimage","url":"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/journalism-header.jpg","contentUrl":"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/journalism-header.jpg","width":1932,"height":1403,"caption":"Freier Journalismus"},{"@type":"BreadcrumbList","@id":"https:\/\/jczeller.com\/de\/journalismus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/jczeller.com\/de\/"},{"@type":"ListItem","position":2,"name":"Journalismus"}]},{"@type":"WebSite","@id":"https:\/\/jczeller.com\/de\/#website","url":"https:\/\/jczeller.com\/de\/","name":"Ihr SEO-Berater und Copywriter.","description":"Kreativit\u00e4t trifft Expertise","publisher":{"@id":"https:\/\/jczeller.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jczeller.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/jczeller.com\/de\/#organization","name":"Ihr SEO-Berater und Copywriter.","url":"https:\/\/jczeller.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jczeller.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/logo-jcz-trans3.png","contentUrl":"https:\/\/jczeller.com\/de\/wp-content\/uploads\/2021\/09\/logo-jcz-trans3.png","width":561,"height":881,"caption":"Ihr SEO-Berater und Copywriter."},"image":{"@id":"https:\/\/jczeller.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/pages\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":30,"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/pages\/80\/revisions"}],"predecessor-version":[{"id":784,"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/pages\/80\/revisions\/784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/media\/81"}],"wp:attachment":[{"href":"https:\/\/jczeller.com\/de\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}